{"id":85134,"count":1,"description":"","link":"https:\/\/www.enerjigazetesi.ist\/en\/enerji-piyasas\u0131\/dogalgaz-ve-soba-zehirlenmeleri\/","name":"do\u011falgaz ve soba zehirlenmeleri","slug":"dogalgaz-ve-soba-zehirlenmeleri","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/tags\/85134"}],"collection":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/posts?tags=85134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}