{"id":34366,"count":1,"description":"","link":"https:\/\/www.enerjigazetesi.ist\/en\/enerji-piyasas\u0131\/enerji-santrali-tel-orgusu\/","name":"enerji santrali tel \u00f6rg\u00fcs\u00fc","slug":"enerji-santrali-tel-orgusu","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/tags\/34366"}],"collection":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/posts?tags=34366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}