{"id":30243,"count":1,"description":"","link":"https:\/\/www.enerjigazetesi.ist\/en\/enerji-piyasas\u0131\/bulgaristan-nukleer-enerjisi\/","name":"Bulgaristan N\u00fckleer enerjisi","slug":"bulgaristan-nukleer-enerjisi","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/tags\/30243"}],"collection":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/posts?tags=30243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}