{"id":117794,"count":1,"description":"","link":"https:\/\/www.enerjigazetesi.ist\/en\/enerji-piyasas\u0131\/depolama-faaliyetleri-yonetmeligi\/","name":"Depolama Faaliyetleri Y\u00f6netmeli\u011fi","slug":"depolama-faaliyetleri-yonetmeligi","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/tags\/117794"}],"collection":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/posts?tags=117794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}