{"id":116484,"count":1,"description":"","link":"https:\/\/www.enerjigazetesi.ist\/en\/enerji-piyasas\u0131\/bolgesel-elektrik-ticareti\/","name":"b\u00f6lgesel elektrik ticareti","slug":"bolgesel-elektrik-ticareti","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/tags\/116484"}],"collection":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/posts?tags=116484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}