{"id":61505,"date":"2017-02-01T18:11:26","date_gmt":"2017-02-01T15:11:26","guid":{"rendered":"https:\/\/www.enerjigazetesi.ist\/?p=61505"},"modified":"2017-02-01T18:11:26","modified_gmt":"2017-02-01T15:11:26","slug":"enervis-muhendislere-enerji-verimliligi-egitimi-veriyor","status":"publish","type":"post","link":"https:\/\/www.enerjigazetesi.ist\/en\/enervis-muhendislere-enerji-verimliligi-egitimi-veriyor\/","title":{"rendered":"(Turkish) Enervis, M\u00fchendislere Enerji Verimlili\u011fi E\u011fitimi Veriyor"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.enerjigazetesi.ist\/tr\/wp-json\/wp\/v2\/posts\/61505\" class=\"qtranxs-available-language-link qtranxs-available-language-link-tr\" title=\"Turkish\">Turkish<\/a>. For the sake of viewer convenience, the content is shown below in the alternative language. You may click the link to switch the active language.<\/p><p><strong>EWE Turkey Holding\u2019e ba\u011fl\u0131 enerji verimlili\u011fi dan\u0131\u015fmanl\u0131\u011f\u0131 \u015firketi Enervis taraf\u0131ndan yenilenebilir enerji ve enerji verimlili\u011fi kapsam\u0131nda bir e\u011fitim d\u00fczenlendi. Ge\u00e7ti\u011fimiz g\u00fcnlerde Bursa Makine M\u00fchendisleri Odas\u0131\u2019nda ger\u00e7ekle\u015fen e\u011fitime, \u00e7e\u015fitli sekt\u00f6rlerde \u00e7al\u0131\u015fan 50\u2019ye yak\u0131n m\u00fchendis ve m\u00fchendis y\u00f6netici kat\u0131ld\u0131. Daha \u00f6nce Organize Sanayi B\u00f6lgesi\u2019nde(O.S.B) e\u011fitimler d\u00fczenleyen Enervis, e\u011fitimlerine yenilenebilir enerji ba\u015fl\u0131\u011f\u0131n\u0131 da ekleyerek 2017 boyunca devam edecek.<\/strong><\/p>\n<p>T\u00fcrkiye\u2019de enerji verimlili\u011fi alan\u0131nda geli\u015ftirdi\u011fi projelerle ad\u0131ndan s\u00f6z ettiren <strong>Enervis<\/strong>, <strong>Bursa Makine M\u00fchendisleri Odas\u0131\u2019nda<\/strong> bir e\u011fitim d\u00fczenledi. Daha \u00f6nce O.S.B\u2019lerde enerji verimlili\u011fi hakk\u0131nda e\u011fitimler veren Enervis, MMO\u2019da d\u00fczenledi\u011fi e\u011fitime, yenilenebil<a href=\"https:\/\/www.enerjigazetesi.ist\/wp-content\/uploads\/2017\/02\/enervis-muhendislere-enerji-verimliligi-egitimi-veriyor.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-61506\" src=\"https:\/\/www.enerjigazetesi.ist\/wp-content\/uploads\/2017\/02\/enervis-muhendislere-enerji-verimliligi-egitimi-veriyor-300x200.jpg\" alt=\"enervis-muhendislere-enerji-verimliligi-egitimi-veriyor\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.enerjigazetesi.ist\/wp-content\/uploads\/2017\/02\/enervis-muhendislere-enerji-verimliligi-egitimi-veriyor-300x200.jpg 300w, https:\/\/www.enerjigazetesi.ist\/wp-content\/uploads\/2017\/02\/enervis-muhendislere-enerji-verimliligi-egitimi-veriyor-1024x682.jpg 1024w, https:\/\/www.enerjigazetesi.ist\/wp-content\/uploads\/2017\/02\/enervis-muhendislere-enerji-verimliligi-egitimi-veriyor-500x333.jpg 500w, https:\/\/www.enerjigazetesi.ist\/wp-content\/uploads\/2017\/02\/enervis-muhendislere-enerji-verimliligi-egitimi-veriyor-75x50.jpg 75w, https:\/\/www.enerjigazetesi.ist\/wp-content\/uploads\/2017\/02\/enervis-muhendislere-enerji-verimliligi-egitimi-veriyor.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>ir enerji konusunu da ekledi. Ge\u00e7ti\u011fimiz g\u00fcnlerde d\u00fczenlenen etkinli\u011fe, \u00e7e\u015fitli sekt\u00f6rlerde \u00e7al\u0131\u015fan 50\u2019nin \u00fczerinde m\u00fchendis ve y\u00f6netici kat\u0131ld\u0131. <strong>Enervis <\/strong>b\u00fcnyesinde \u00e7al\u0131\u015fan e\u011fitimci ve uzman m\u00fchendisler, kapan\u0131\u015f konu\u015fmalar\u0131n\u0131n ard\u0131ndan soru cevap \u015feklinde kat\u0131l\u0131mc\u0131lar\u0131n enerji verimlili\u011fi ve yenilenebilir enerji ile ilgili merak ettiklerini yan\u0131tlad\u0131.<\/p>\n<p>Etkinlik hakk\u0131nda konu\u015fan <strong>Enervis Genel M\u00fcd\u00fcr\u00fc Osman Kipo\u011flu<\/strong>;<\/p>\n<p><em>\u201cSanayi, Bursa ekonomisinin temelini olu\u015fturuyor. Bursa\u2019da faaliyet g\u00f6steren sanayi kurulu\u015flar\u0131 i\u00e7in de enerji verimlili\u011fi vazge\u00e7ilmez bir unsur. D\u00fczenledi\u011fimiz e\u011fitimlerle farkl\u0131 sekt\u00f6rlerde \u00e7al\u0131\u015fan m\u00fchendis ve y\u00f6netici arkada\u015flar\u0131m\u0131z\u0131 bilin\u00e7lendirerek, enerji tasarrufu yapmalar\u0131na yard\u0131mc\u0131 olmay\u0131 ama\u00e7l\u0131yoruz. Sadece hayata ge\u00e7irdi\u011fimiz projelerle de\u011fil, d\u00fczenledi\u011fimiz e\u011fitimlerle de enerji verimlili\u011fi ve yenilenebilir enerji konular\u0131n\u0131n hem sekt\u00f6r hem de \u00fclkemiz sanayi i\u00e7in ne kadar \u00f6nemli oldu\u011funu anlatmaya \u00e7al\u0131\u015f\u0131yoruz.\u201d<\/em> diye konu\u015ftu.<\/p>\n<p><strong>Bursa M\u00fchendisler Odas\u0131\u2019nda \u2018<\/strong><em>End\u00fcstriyel \u0130\u015fletmelerde Enerji Geri Kazan\u0131m\u0131\u2019, \u2018Enerji Verimlili\u011fi Dan\u0131\u015fmanl\u0131k Faaliyetleri\u2019, \u2018Yenilenebilir Enerji Kullan\u0131m\u0131 ( G\u00fcne\u015f Enerjisi) ve At\u0131k Hava Filtrasyonu\u2019 ana ba\u015fl\u0131klar\u0131nda e\u011fitimler ger\u00e7ekle\u015ftirildi.<\/em><\/p>\n<p>Yat\u0131r\u0131mlar M\u00fcd\u00fcr Yard\u0131mc\u0131s\u0131 Serkan Bereket, G\u00fcne\u015f Enerji Sistemleri Birim Y\u00f6neticisi Umut G\u00fcrsan, Mekanik \u0130\u015fler Birim Y\u00f6neticisi U\u011fur Kozan, Enerji Verimlili\u011fi ve Y\u00f6netim Birim Y\u00f6neticisi Sedat Vatanda\u015f ve Enervis Genel M\u00fcd\u00fcr\u00fc Osman Kipo\u011flu Enervis b\u00fcnyesinde \u00e7al\u0131\u015fan ve e\u011fitim veren isimler aras\u0131nda yer ald\u0131. Etkinli\u011fin moderat\u00f6rl\u00fc\u011f\u00fcn\u00fc ise Yunus Demirci \u00fcstlendi.<\/p>\n<p>Enervis, e\u011fitimlerine makine, elektrik, end\u00fcstri ve tekstil m\u00fchendisleri i\u00e7in d\u00fczenleyece\u011fi seminerler dizisi \u015feklinde\u00a0s\u00fcrecek.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Turkish. For the sake of viewer convenience, the content is shown below in the alternative language. You may click the link to switch the active language.EWE Turkey Holding\u2019e ba\u011fl\u0131 enerji verimlili\u011fi dan\u0131\u015fmanl\u0131\u011f\u0131 \u015firketi Enervis taraf\u0131ndan yenilenebilir enerji ve enerji verimlili\u011fi kapsam\u0131nda bir e\u011fitim d\u00fczenlendi. Ge\u00e7ti\u011fimiz g\u00fcnlerde Bursa Makine [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":61506,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[53,52],"tags":[63,67,1009,2698,165,12,2397,12090,793,105],"views":1177,"_links":{"self":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/posts\/61505"}],"collection":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/comments?post=61505"}],"version-history":[{"count":1,"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/posts\/61505\/revisions"}],"predecessor-version":[{"id":61507,"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/posts\/61505\/revisions\/61507"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/media\/61506"}],"wp:attachment":[{"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/media?parent=61505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/categories?post=61505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.enerjigazetesi.ist\/en\/wp-json\/wp\/v2\/tags?post=61505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}